{"id":74,"count":1,"description":"","link":"https:\/\/blog.salesflare.com\/pt\/announcement","name":"An\u00fancio","slug":"announcement","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Announcement Archives | Salesflare Blog<\/title>\n<meta name=\"description\" content=\"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/categories\/74\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Announcement Archives | Salesflare Blog\" \/>\n<meta property=\"og:description\" content=\"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/categories\/74\" \/>\n<meta property=\"og:site_name\" content=\"Salesflare Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2025\/01\/sf-opengraph-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@salesflare\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement\",\"name\":\"Announcement Archives | Salesflare Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#website\"},\"description\":\"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.salesflare.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Announcement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/\",\"name\":\"Salesflare Blog\",\"description\":\"On sales, CRM and lead generation.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#organization\",\"name\":\"Salesflare\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/sf-logo-900x160-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.salesflare.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/sf-logo-900x160-1.jpg\",\"width\":900,\"height\":160,\"caption\":\"Salesflare\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salesflare\\\/\",\"https:\\\/\\\/x.com\\\/salesflare\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salesflare\",\"https:\\\/\\\/www.youtube.com\\\/@salesflare\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Announcement Archives | Salesflare Blog","description":"Navegue pelos arquivos de An\u00fancios no Blog Salesflare para descobrir todos os artigos relacionados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/categories\/74","og_locale":"pt_BR","og_type":"article","og_title":"Announcement Archives | Salesflare Blog","og_description":"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.","og_url":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/categories\/74","og_site_name":"Salesflare Blog","og_image":[{"width":1200,"height":630,"url":"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2025\/01\/sf-opengraph-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@salesflare","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.salesflare.com\/announcement","url":"https:\/\/blog.salesflare.com\/announcement","name":"Arquivos de an\u00fancios | Blog do Salesflare","isPartOf":{"@id":"https:\/\/blog.salesflare.com\/fr\/#website"},"description":"Navegue pelos arquivos de An\u00fancios no Blog Salesflare para descobrir todos os artigos relacionados.","breadcrumb":{"@id":"https:\/\/blog.salesflare.com\/announcement#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.salesflare.com\/announcement#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.salesflare.com\/"},{"@type":"ListItem","position":2,"name":"Announcement"}]},{"@type":"WebSite","@id":"https:\/\/blog.salesflare.com\/fr\/#website","url":"https:\/\/blog.salesflare.com\/fr\/","name":"Blog Salesflare","description":"Em vendas, CRM e gera\u00e7\u00e3o de leads.","publisher":{"@id":"https:\/\/blog.salesflare.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.salesflare.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.salesflare.com\/fr\/#organization","name":"Salesflare","url":"https:\/\/blog.salesflare.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.salesflare.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2018\/09\/sf-logo-900x160-1.jpg","contentUrl":"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2018\/09\/sf-logo-900x160-1.jpg","width":900,"height":160,"caption":"Salesflare"},"image":{"@id":"https:\/\/blog.salesflare.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salesflare\/","https:\/\/x.com\/salesflare","https:\/\/www.linkedin.com\/company\/salesflare","https:\/\/www.youtube.com\/@salesflare"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/categories\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/posts?categories=74"},{"href":"https:\/\/blog.salesflare.com\/pt\/wp-json\/wp\/v2\/entities?categories=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}