{"id":74,"count":1,"description":"","link":"https:\/\/blog.salesflare.com\/ja\/announcement","name":"\u767a\u8868","slug":"announcement","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Announcement Archives | Salesflare Blog<\/title>\n<meta name=\"description\" content=\"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/categories\/74\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Announcement Archives | Salesflare Blog\" \/>\n<meta property=\"og:description\" content=\"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/categories\/74\" \/>\n<meta property=\"og:site_name\" content=\"Salesflare Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2025\/01\/sf-opengraph-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@salesflare\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement\",\"name\":\"Announcement Archives | Salesflare Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#website\"},\"description\":\"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/announcement#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.salesflare.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Announcement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/\",\"name\":\"Salesflare Blog\",\"description\":\"On sales, CRM and lead generation.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#organization\",\"name\":\"Salesflare\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.salesflare.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/sf-logo-900x160-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.salesflare.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/sf-logo-900x160-1.jpg\",\"width\":900,\"height\":160,\"caption\":\"Salesflare\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.salesflare.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/salesflare\\\/\",\"https:\\\/\\\/x.com\\\/salesflare\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salesflare\",\"https:\\\/\\\/www.youtube.com\\\/@salesflare\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Announcement Archives | Salesflare Blog","description":"Salesflare\u30d6\u30ed\u30b0\u306e\u30a2\u30ca\u30a6\u30f3\u30b9\u30fb\u30a2\u30fc\u30ab\u30a4\u30d6\u3092\u95b2\u89a7\u3057\u3066\u3001\u3059\u3079\u3066\u306e\u95a2\u9023\u8a18\u4e8b\u3092\u767a\u898b\u3057\u3066\u304f\u3060\u3055\u3044\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/categories\/74","og_locale":"ja_JP","og_type":"article","og_title":"Announcement Archives | Salesflare Blog","og_description":"Browse through the Announcement archives on the Salesflare Blog to discover all related articles.","og_url":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/categories\/74","og_site_name":"Salesflare Blog","og_image":[{"width":1200,"height":630,"url":"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2025\/01\/sf-opengraph-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@salesflare","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.salesflare.com\/announcement","url":"https:\/\/blog.salesflare.com\/announcement","name":"\u304a\u77e5\u3089\u305b\u30a2\u30fc\u30ab\u30a4\u30d6\uff5cSalesflare\u30d6\u30ed\u30b0","isPartOf":{"@id":"https:\/\/blog.salesflare.com\/fr\/#website"},"description":"Salesflare\u30d6\u30ed\u30b0\u306e\u30a2\u30ca\u30a6\u30f3\u30b9\u30fb\u30a2\u30fc\u30ab\u30a4\u30d6\u3092\u95b2\u89a7\u3057\u3066\u3001\u3059\u3079\u3066\u306e\u95a2\u9023\u8a18\u4e8b\u3092\u767a\u898b\u3057\u3066\u304f\u3060\u3055\u3044\u3002","breadcrumb":{"@id":"https:\/\/blog.salesflare.com\/announcement#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.salesflare.com\/announcement#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.salesflare.com\/"},{"@type":"ListItem","position":2,"name":"Announcement"}]},{"@type":"WebSite","@id":"https:\/\/blog.salesflare.com\/fr\/#website","url":"https:\/\/blog.salesflare.com\/fr\/","name":"Salesflare\u30d6\u30ed\u30b0","description":"\u30bb\u30fc\u30eb\u30b9\u3001CRM\u3001\u30ea\u30fc\u30c9\u30b8\u30a7\u30cd\u30ec\u30fc\u30b7\u30e7\u30f3\u306b\u3064\u3044\u3066\u3002","publisher":{"@id":"https:\/\/blog.salesflare.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.salesflare.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/blog.salesflare.com\/fr\/#organization","name":"Salesflare","url":"https:\/\/blog.salesflare.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/blog.salesflare.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2018\/09\/sf-logo-900x160-1.jpg","contentUrl":"https:\/\/blog.salesflare.com\/wp-content\/uploads\/2018\/09\/sf-logo-900x160-1.jpg","width":900,"height":160,"caption":"Salesflare"},"image":{"@id":"https:\/\/blog.salesflare.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/salesflare\/","https:\/\/x.com\/salesflare","https:\/\/www.linkedin.com\/company\/salesflare","https:\/\/www.youtube.com\/@salesflare"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/categories\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/posts?categories=74"},{"href":"https:\/\/blog.salesflare.com\/ja\/wp-json\/wp\/v2\/entities?categories=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}